{"id":2937,"date":"2016-01-28T15:13:26","date_gmt":"2016-01-28T14:13:26","guid":{"rendered":"https:\/\/mgi-fr.com\/?p=2937"},"modified":"2026-06-25T17:59:51","modified_gmt":"2026-06-25T15:59:51","slug":"packaging-gl","status":"publish","type":"post","link":"https:\/\/mgi-fr.com\/en\/gallery\/packaging-gl\/","title":{"rendered":"Gallery: Packaging"},"content":{"rendered":"<style>.kb-row-layout-id2937_d9bb19-85 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id2937_d9bb19-85 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id2937_d9bb19-85 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1600px;margin-left:auto;margin-right:auto;padding-top:20px;padding-bottom:20px;min-height:300px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_d9bb19-85{background-image:url('https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/Samples-Packaging-Etoile.webp');background-size:cover;background-position:45% 23%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2937_d9bb19-85 > .kt-row-layout-overlay{opacity:0.57;background:linear-gradient(180deg, rgba(255, 255, 255, 0) 51%, var(--global-palette9) 83%);}.kb-row-layout-id2937_d9bb19-85 ,.kb-row-layout-id2937_d9bb19-85 h1,.kb-row-layout-id2937_d9bb19-85 h2,.kb-row-layout-id2937_d9bb19-85 h3,.kb-row-layout-id2937_d9bb19-85 h4,.kb-row-layout-id2937_d9bb19-85 h5,.kb-row-layout-id2937_d9bb19-85 h6{color:#ffffff;}.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id2937_d9bb19-85 > .kt-row-column-wrap{min-height:300px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id2937_d9bb19-85 > .kt-row-column-wrap{min-height:300px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id2937_d9bb19-85 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2937_d9bb19-85 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom\">\n<style>.kadence-column2937_b9be31-fd > .kt-inside-inner-col,.kadence-column2937_b9be31-fd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2937_b9be31-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2937_b9be31-fd > .kt-inside-inner-col{flex-direction:column;}.kadence-column2937_b9be31-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2937_b9be31-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2937_b9be31-fd{position:relative;}@media all and (max-width: 1024px){.kadence-column2937_b9be31-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2937_b9be31-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2937_b9be31-fd inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d, .wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d[data-kb-block=\"kb-adv-heading2937_131e67-3d\"]{text-align:center;font-size:3em;line-height:0.8em;font-style:normal;text-transform:uppercase;text-shadow:1px 1px 20px rgba(221,215,215,0.7);}.wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d[data-kb-block=\"kb-adv-heading2937_131e67-3d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d[data-kb-block=\"kb-adv-heading2937_131e67-3d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d, .wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d[data-kb-block=\"kb-adv-heading2937_131e67-3d\"]{text-shadow:1px 1px 20px rgba(221,215,215,0.7);font-size:2.5em;line-height:0.8em;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d, .wp-block-kadence-advancedheading.kt-adv-heading2937_131e67-3d[data-kb-block=\"kb-adv-heading2937_131e67-3d\"]{text-shadow:1px 1px 20px rgba(221,215,215,0.7);font-size:2em;line-height:1em;}}<\/style>\n<h1 class=\"kt-adv-heading2937_131e67-3d wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading2937_131e67-3d\">Packaging<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2937_5d04e5-83 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2937_5d04e5-83 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2937_5d04e5-83 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_5d04e5-83 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2937_5d04e5-83 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2937_5d04e5-83 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2937_5d04e5-83 alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2937_e53682-bc > .kt-inside-inner-col,.kadence-column2937_e53682-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2937_e53682-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2937_e53682-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column2937_e53682-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2937_e53682-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2937_e53682-bc{position:relative;}@media all and (max-width: 1024px){.kadence-column2937_e53682-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2937_e53682-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2937_e53682-bc inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88, .wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88[data-kb-block=\"kb-adv-heading2937_8db987-88\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88[data-kb-block=\"kb-adv-heading2937_8db987-88\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2937_8db987-88[data-kb-block=\"kb-adv-heading2937_8db987-88\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h5 class=\"kt-adv-heading2937_8db987-88 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2937_8db987-88\">Diff\u00e9renciez-vous, pour \u00e9merger sur le march\u00e9 du packaging<\/h5>\n\n\n<style>.kb-row-layout-id2937_be9dbb-31 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2937_be9dbb-31 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2937_be9dbb-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-right:20px;padding-bottom:50px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_be9dbb-31 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2937_be9dbb-31 > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2937_be9dbb-31 > .kt-row-column-wrap{padding-right:5px;padding-left:5px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2937_be9dbb-31 alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2937_b7b17c-fc > .kt-inside-inner-col,.kadence-column2937_b7b17c-fc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2937_b7b17c-fc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2937_b7b17c-fc > .kt-inside-inner-col{flex-direction:column;}.kadence-column2937_b7b17c-fc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2937_b7b17c-fc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2937_b7b17c-fc{position:relative;}@media all and (max-width: 1024px){.kadence-column2937_b7b17c-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2937_b7b17c-fc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2937_b7b17c-fc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93, .wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93[data-kb-block=\"kb-adv-heading2937_b36e36-93\"]{padding-bottom:20px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93[data-kb-block=\"kb-adv-heading2937_b36e36-93\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2937_b36e36-93[data-kb-block=\"kb-adv-heading2937_b36e36-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading2937_b36e36-93 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2937_b36e36-93\">D\u00e9couvrez ci-dessous quelques exemples de packagings, r\u00e9alis\u00e9s avec les technologies MGI. <\/h6>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-2937_19b3e8-9e{margin-top:5%;margin-right:5%;margin-bottom:5%;margin-left:5%;}.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-2937_19b3e8-9e{margin:-50px;}.kb-gallery-type-masonry.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item{padding:50px;}.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-2937_19b3e8-9e .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:1em;text-transform:none;color:var(--global-palette5, #4A5568);}.kb-gallery-caption-style-cover-hover.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-below.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:rgba(248, 249, 250, 0.9);}@media all and (max-width: 1024px){.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-2937_19b3e8-9e{margin-top:0%;margin-right:0%;margin-bottom:0%;margin-left:0%;}}@media all and (max-width: 1024px){.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:0.5em;}}@media all and (max-width: 767px){.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-2937_19b3e8-9e{margin-top:0%;margin-right:0%;margin-bottom:0%;margin-left:0%;}.kb-gallery-id-2937_19b3e8-9e .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:0.5em;}}<\/style><div class=\"kb-gallery-wrap-id-2937_19b3e8-9e alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-2937_19b3e8-9e kb-gallery-caption-style-cover-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg\" data-description=\"Cr\u00e9ation de Point 44. Etui en carton plat, imprim\u00e9 en offset, puis ennobli sur presse d\u2019ennoblissement num\u00e9rique MGI JETvarnish 3D Evo - Vernis s\u00e9lectif UV num\u00e9rique en relief et d\u00e9pose d\u2019argenture \u00e0 chaud, en relief\" data-alt=\"Photos d&#039;un emballage de luxe embelli noire et rose, avec du vernis - ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:907px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:80%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg\" width=\"907\" height=\"728\" alt=\"Photos d&#039;un emballage de luxe embelli noire et rose, avec du vernis - ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg\" data-id=\"2752\" class=\"wp-image-2752\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg 907w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3-400x321.jpg 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3-768x616.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3-15x12.jpg 15w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Cr\u00e9ation de Point 44. Etui en carton plat, imprim\u00e9 en offset, puis ennobli sur presse d\u2019ennoblissement num\u00e9rique MGI JETvarnish 3D Evo &#8211; Vernis s\u00e9lectif UV num\u00e9rique en relief et d\u00e9pose d\u2019argenture \u00e0 chaud, en relief<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5.jpg\" data-description=\"Photo de packaging de joaillerie - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" data-alt=\"Packaging de bijoux bleu orn\u00e9 d&#039;un paon - imprim\u00e9 ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1000px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:84%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5.jpg\" width=\"1000\" height=\"848\" alt=\"Packaging de bijoux bleu orn\u00e9 d&#039;un paon - imprim\u00e9 ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5.jpg\" data-id=\"6618\" class=\"wp-image-6618\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5.jpg 1000w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5-400x339.jpg 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5-768x651.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Jewelry-Peacock-5-14x12.jpg 14w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging de joaillerie &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2.jpg\" data-description=\"Photo de packaging de parfum - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" data-alt=\"Photo d&#039;un packaging de parfum rouge, avec un coeur en dorure et en vernis, ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:821px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:146%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2.jpg\" width=\"821\" height=\"1200\" alt=\"Photo d&#039;un packaging de parfum rouge, avec un coeur en dorure et en vernis, ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2.jpg\" data-id=\"6613\" class=\"wp-image-6613\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2.jpg 821w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2-274x400.jpg 274w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2-701x1024.jpg 701w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2-768x1123.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Love-2-8x12.jpg 8w\" sizes=\"auto, (max-width: 821px) 100vw, 821px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging de parfum &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3.jpg\" data-description=\"Photo de packaging de parfum - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" data-alt=\"Photo d&#039;un packaging de parfum bleu, avec nom en dorure et rehauts de vernis, ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1200px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:81%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3.jpg\" width=\"1200\" height=\"972\" alt=\"Photo d&#039;un packaging de parfum bleu, avec nom en dorure et rehauts de vernis, ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3.jpg\" data-id=\"6615\" class=\"wp-image-6615\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3.jpg 1200w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3-400x324.jpg 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3-1024x829.jpg 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3-768x622.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-Luna-3-15x12.jpg 15w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging de parfum &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2.jpg\" data-description=\"Photo de packagings de sardines - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" data-alt=\"Photo de 3 packagings de sardines color\u00e9s, avec dorure et vernis, ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1200px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:70%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2.jpg\" width=\"1200\" height=\"848\" alt=\"Photo de 3 packagings de sardines color\u00e9s, avec dorure et vernis, ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2.jpg\" data-id=\"6601\" class=\"wp-image-6601\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2.jpg 1200w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2-400x283.jpg 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2-1024x724.jpg 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2-768x543.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2016\/01\/Sample-MGI-Packaging-Food-Sardines-x3-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packagings de sardines &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2.jpg\" data-description=\"Photo de packaging - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" data-alt=\"Photo d&#039;un packaging de rouge \u00e0 l\u00e8vres noir et rose, avec dorure rouge et vernis, ennoblissement sur JETvarnish de MGI\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:133%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2.jpg\" width=\"900\" height=\"1200\" alt=\"Photo d&#039;un packaging de rouge \u00e0 l\u00e8vres noir et rose, avec dorure rouge et vernis, ennoblissement sur JETvarnish de MGI\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2.jpg\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2.jpg\" data-id=\"6608\" class=\"wp-image-6608\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2.jpg 900w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2-300x400.jpg 300w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2-768x1024.jpg 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Lipstick-Magic-2-9x12.jpg 9w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03.webp\" data-description=\"Photo de packaging de Whiskey - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1200px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:75%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03.webp\" width=\"1200\" height=\"901\" alt=\"\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03.webp\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03.webp\" data-id=\"6634\" class=\"wp-image-6634\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03.webp 1200w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03-400x300.webp 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03-1024x769.webp 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03-768x577.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Whisky-Blunten-03-16x12.webp 16w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging de Whiskey &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05.webp\" data-description=\"Photo de packaging - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1200px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:75%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05.webp\" width=\"1200\" height=\"911\" alt=\"\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05.webp\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05.webp\" data-id=\"6614\" class=\"wp-image-6614\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05.webp 1200w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05-400x304.webp 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05-1024x777.webp 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05-768x583.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Cosmetic-Perfume-AW-05-16x12.webp 16w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex.webp\" data-description=\"Photo de packaging pharmaceutique - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1200px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:42%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex.webp\" width=\"1200\" height=\"511\" alt=\"\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex.webp\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex.webp\" data-id=\"6694\" class=\"wp-image-6694\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex.webp 1200w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex-400x170.webp 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex-1024x436.webp 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex-768x327.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Medicine-Mediflex-18x8.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging pharmaceutique &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka.webp\" data-description=\"Photo de packaging - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:962px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:124%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka.webp\" width=\"962\" height=\"1200\" alt=\"\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka.webp\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka.webp\" data-id=\"6695\" class=\"wp-image-6695\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka.webp 962w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka-321x400.webp 321w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka-821x1024.webp 821w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka-768x958.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Food-Coffee-Lemoka-10x12.webp 10w\" sizes=\"auto, (max-width: 962px) 100vw, 962px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01.webp\" data-description=\"Photo de packaging - embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\" style=\"max-width:1065px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:112%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01.webp\" width=\"1065\" height=\"1200\" alt=\"\" data-full-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01.webp\" data-light-image=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01.webp\" data-id=\"6598\" class=\"wp-image-6598\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01.webp 1065w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01-355x400.webp 355w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01-909x1024.webp 909w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01-768x865.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/07\/Sample-MGI-Packaging-Alcohol-Champagne-Duraisin-01-11x12.webp 11w\" sizes=\"auto, (max-width: 1065px) 100vw, 1065px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Photo de packaging &#8211; embellissement (vernis UV et dorure \u00e0 chaud 100% num\u00e9riques) sur JETvarnish de MGI Digital Technology<\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<!--more-->\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad, .wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad[data-kb-block=\"kb-adv-heading2937_1e107a-ad\"]{margin-right:2%;margin-left:2%;text-align:center;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad[data-kb-block=\"kb-adv-heading2937_1e107a-ad\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2937_1e107a-ad[data-kb-block=\"kb-adv-heading2937_1e107a-ad\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading2937_1e107a-ad wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2937_1e107a-ad\">\u00e9quipements adressant le march\u00e9<\/h4>\n\n\n<style>.kb-row-layout-id2937_3eb10d-1b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2937_3eb10d-1b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2937_3eb10d-1b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:60px;padding-right:20px;padding-bottom:25px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_3eb10d-1b > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep{height:20px;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep svg{width:50%;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep svg{fill:var(--global-palette4, #2D3748)!important;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-top-sep{height:5px;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-top-sep svg{width:50%;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-top-sep svg{fill:var(--global-palette4, #2D3748)!important;}@media all and (max-width: 1024px){.kb-row-layout-id2937_3eb10d-1b > .kt-row-column-wrap{padding-right:15px;padding-left:15px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id2937_3eb10d-1b > .kt-row-column-wrap{padding-right:5px;padding-left:5px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-bottom-sep svg{width:%;}.kb-row-layout-id2937_3eb10d-1b .kt-row-layout-top-sep svg{width:80%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2937_3eb10d-1b alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-top-sep kt-row-sep-type-cti\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M500,2l500,98l-1000,0l500,-98Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2937_ffd565-60 > .kt-inside-inner-col,.kadence-column2937_ffd565-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2937_ffd565-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2937_ffd565-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2937_ffd565-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2937_ffd565-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2937_ffd565-60{position:relative;}@media all and (max-width: 1024px){.kadence-column2937_ffd565-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2937_ffd565-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2937_ffd565-60 inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><style>.kb-posts-id-2937_8bf794-d9 .loop-entry{background:transparent;box-shadow:none;}.kb-posts-id-2937_8bf794-d9 .loop-entry > .entry-content-wrap{padding:0px;}.kb-posts-id-2937_8bf794-d9 .loop-entry .post-thumbnail{margin-bottom:1em;}.kb-posts-id-2937_8bf794-d9 .kb-post-list-item{display:grid;}<\/style><ul class=\"wp-block-kadence-posts kb-posts kadence-posts-list kb-posts-id-2937_8bf794-d9 content-wrap grid-cols kb-posts-style-unboxed grid-sm-col-2 grid-lg-col-3 item-image-style-above\"><li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-1319 post type-post status-publish format-standard has-post-thumbnail hentry category-equipements tag-edition tag-embellissement-numerique tag-imprimes-commerciaux tag-imprimes-photos tag-jetvarnish-3d-evo tag-packaging tag-sous-traitance tag-web-to-print\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-1-2\" href=\"https:\/\/mgi-fr.com\/en\/equipment\/jetvarnish-3d-evo\/\" aria-label=\"JETvarnish 3D Evo\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/07\/MGI-JETVARNISH-3D-Evo-26-03-25-1.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"JETvarnish 3D Evo\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/07\/MGI-JETVARNISH-3D-Evo-26-03-25-1.webp 800w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/07\/MGI-JETVARNISH-3D-Evo-26-03-25-1-400x200.webp 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/07\/MGI-JETVARNISH-3D-Evo-26-03-25-1-768x384.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/07\/MGI-JETVARNISH-3D-Evo-26-03-25-1-18x9.webp 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t<h6 class=\"entry-title\"><a href=\"https:\/\/mgi-fr.com\/en\/equipment\/jetvarnish-3d-evo\/\" rel=\"bookmark\">JETvarnish 3D Evo<\/a><\/h6><\/header><!-- .entry-header -->\n<footer class=\"entry-footer\">\n\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-9800 post type-post status-publish format-standard has-post-thumbnail hentry category-equipements tag-jetvarnish-3d tag-jetvarnish-3d-evo tag-mgi-approve tag-mgi-connect tag-mgi-dashboard tag-mgi-jetforce tag-packaging tag-web-to-print\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-1-2\" href=\"https:\/\/mgi-fr.com\/en\/equipment\/mgi-connect\/\" aria-label=\"MGI Cloud Solutions\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"3352\" height=\"2066\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12.png\" class=\"attachment-full size-full wp-post-image\" alt=\"MGI Cloud Solutions\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12.png 3352w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-400x247.png 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-1024x631.png 1024w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-768x473.png 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-1536x947.png 1536w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-2048x1262.png 2048w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2024\/02\/Capture-decran-2023-12-21-a-17.49.12-18x12.png 18w\" sizes=\"auto, (max-width: 3352px) 100vw, 3352px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t<h6 class=\"entry-title\"><a href=\"https:\/\/mgi-fr.com\/en\/equipment\/mgi-connect\/\" rel=\"bookmark\">MGI Cloud Solutions<\/a><\/h6><\/header><!-- .entry-header -->\n<footer class=\"entry-footer\">\n\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-1643 post type-post status-publish format-standard has-post-thumbnail hentry category-equipements tag-alphajet tag-edition tag-embellissement-numerique tag-impression-numerique tag-imprimes-commerciaux tag-imprimes-photos tag-packaging tag-sous-traitance tag-web-to-print\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-1-2\" href=\"https:\/\/mgi-fr.com\/en\/equipment\/alphajet\/\" aria-label=\"AlphaJET\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/08\/MGI-ALPHAJET-28-03-2025.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"AlphaJET\" srcset=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/08\/MGI-ALPHAJET-28-03-2025.webp 800w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/08\/MGI-ALPHAJET-28-03-2025-400x200.webp 400w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/08\/MGI-ALPHAJET-28-03-2025-768x384.webp 768w, https:\/\/mgi-fr.com\/wp-content\/uploads\/2018\/08\/MGI-ALPHAJET-28-03-2025-18x9.webp 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t<h6 class=\"entry-title\"><a href=\"https:\/\/mgi-fr.com\/en\/equipment\/alphajet\/\" rel=\"bookmark\">AlphaJET<\/a><\/h6><\/header><!-- .entry-header -->\n<footer class=\"entry-footer\">\n\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<\/ul><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>MGI offers a wide range of digital printing and finishing presses, adapted to the folding carton, microflute and corrugated board markets.<\/p>","protected":false},"author":1,"featured_media":2752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"default","_kad_post_title":"hide","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[41],"tags":[13,31,10,35,16],"class_list":["post-2937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galerie","tag-alphajet","tag-jetvarnish-3d","tag-jetvarnish-3d-evo","tag-jetvarnish-3d-web","tag-packaging"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galerie: Packaging -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mgi-fr.com\/en\/gallery\/packaging-gl\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galerie: Packaging -\" \/>\n<meta property=\"og:description\" content=\"MGI propose toute une gamme de presses num\u00e9riques d\u2019impression et d\u2019ennoblissement, adapt\u00e9es tant aux march\u00e9s du carton plat, qu\u2019\u00e0 ceux de la micro-cannelure ou du carton ondul\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mgi-fr.com\/en\/gallery\/packaging-gl\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/MGIonline\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-28T14:13:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T15:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"907\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Corinne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MGI_HQ\" \/>\n<meta name=\"twitter:site\" content=\"@MGI_HQ\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/\"},\"author\":{\"name\":\"Corinne\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#\\\/schema\\\/person\\\/41ee3fb954ff7f83e6bddf4a40f00e8c\"},\"headline\":\"Galerie: Packaging\",\"datePublished\":\"2016-01-28T14:13:26+00:00\",\"dateModified\":\"2026-06-25T15:59:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/\"},\"wordCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mgi-fr.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2021-Samples-CLIENT-Etoile-3.jpg\",\"keywords\":[\"AlphaJET\",\"JETvarnish 3D\",\"JETvarnish 3D Evo\",\"JETvarnish 3D Web\",\"Packaging\"],\"articleSection\":[\"Galerie\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/\",\"url\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/\",\"name\":\"Galerie: Packaging -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mgi-fr.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2021-Samples-CLIENT-Etoile-3.jpg\",\"datePublished\":\"2016-01-28T14:13:26+00:00\",\"dateModified\":\"2026-06-25T15:59:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mgi-fr.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2021-Samples-CLIENT-Etoile-3.jpg\",\"contentUrl\":\"https:\\\/\\\/mgi-fr.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/2021-Samples-CLIENT-Etoile-3.jpg\",\"width\":907,\"height\":728,\"caption\":\"Cr\u00e9ation de Point 44. Etui en carton plat, imprim\u00e9 en offset, puis ennobli sur presse d\u2019ennoblissement num\u00e9rique MGI JETvarnish 3D Evo - Vernis s\u00e9lectif UV num\u00e9rique en relief et d\u00e9pose d\u2019argenture \u00e0 chaud, en relief\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/galerie\\\/packaging-gl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mgi-fr.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerie: Packaging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#website\",\"url\":\"https:\\\/\\\/mgi-fr.com\\\/\",\"name\":\"\",\"description\":\"Leader des technologies d\u2019impression et de finitions num\u00e9riques\",\"publisher\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mgi-fr.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#organization\",\"name\":\"MGI Digital Technology\",\"url\":\"https:\\\/\\\/mgi-fr.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/mgi-nouveau-site.mgi-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-MGI-Blue-Baseline.jpg\",\"contentUrl\":\"http:\\\/\\\/mgi-nouveau-site.mgi-labs.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Logo-MGI-Blue-Baseline.jpg\",\"width\":842,\"height\":595,\"caption\":\"MGI Digital Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/MGIonline\\\/\",\"https:\\\/\\\/x.com\\\/MGI_HQ\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mgi-digital-graphic-technology\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCqJTeVGo2EQ3NOCqFMekydA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mgi-fr.com\\\/#\\\/schema\\\/person\\\/41ee3fb954ff7f83e6bddf4a40f00e8c\",\"name\":\"Corinne\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g\",\"caption\":\"Corinne\"},\"sameAs\":[\"http:\\\/\\\/mgi-test-site.local\"],\"url\":\"https:\\\/\\\/mgi-fr.com\\\/en\\\/author\\\/corinne\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie: Packaging -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mgi-fr.com\/en\/gallery\/packaging-gl\/","og_locale":"en_US","og_type":"article","og_title":"Galerie: Packaging -","og_description":"MGI propose toute une gamme de presses num\u00e9riques d\u2019impression et d\u2019ennoblissement, adapt\u00e9es tant aux march\u00e9s du carton plat, qu\u2019\u00e0 ceux de la micro-cannelure ou du carton ondul\u00e9.","og_url":"https:\/\/mgi-fr.com\/en\/gallery\/packaging-gl\/","article_publisher":"https:\/\/m.facebook.com\/MGIonline\/","article_published_time":"2016-01-28T14:13:26+00:00","article_modified_time":"2026-06-25T15:59:51+00:00","og_image":[{"width":907,"height":728,"url":"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg","type":"image\/jpeg"}],"author":"Corinne","twitter_card":"summary_large_image","twitter_creator":"@MGI_HQ","twitter_site":"@MGI_HQ","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#article","isPartOf":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/"},"author":{"name":"Corinne","@id":"https:\/\/mgi-fr.com\/#\/schema\/person\/41ee3fb954ff7f83e6bddf4a40f00e8c"},"headline":"Galerie: Packaging","datePublished":"2016-01-28T14:13:26+00:00","dateModified":"2026-06-25T15:59:51+00:00","mainEntityOfPage":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/"},"wordCount":30,"publisher":{"@id":"https:\/\/mgi-fr.com\/#organization"},"image":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#primaryimage"},"thumbnailUrl":"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg","keywords":["AlphaJET","JETvarnish 3D","JETvarnish 3D Evo","JETvarnish 3D Web","Packaging"],"articleSection":["Galerie"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/","url":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/","name":"Galerie: Packaging -","isPartOf":{"@id":"https:\/\/mgi-fr.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#primaryimage"},"image":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#primaryimage"},"thumbnailUrl":"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg","datePublished":"2016-01-28T14:13:26+00:00","dateModified":"2026-06-25T15:59:51+00:00","breadcrumb":{"@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mgi-fr.com\/galerie\/packaging-gl\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#primaryimage","url":"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg","contentUrl":"https:\/\/mgi-fr.com\/wp-content\/uploads\/2022\/01\/2021-Samples-CLIENT-Etoile-3.jpg","width":907,"height":728,"caption":"Cr\u00e9ation de Point 44. Etui en carton plat, imprim\u00e9 en offset, puis ennobli sur presse d\u2019ennoblissement num\u00e9rique MGI JETvarnish 3D Evo - Vernis s\u00e9lectif UV num\u00e9rique en relief et d\u00e9pose d\u2019argenture \u00e0 chaud, en relief"},{"@type":"BreadcrumbList","@id":"https:\/\/mgi-fr.com\/galerie\/packaging-gl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mgi-fr.com\/"},{"@type":"ListItem","position":2,"name":"Galerie: Packaging"}]},{"@type":"WebSite","@id":"https:\/\/mgi-fr.com\/#website","url":"https:\/\/mgi-fr.com\/","name":"","description":"The Leader in printing technologies and finishes, digital","publisher":{"@id":"https:\/\/mgi-fr.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mgi-fr.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mgi-fr.com\/#organization","name":".","url":"https:\/\/mgi-fr.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mgi-fr.com\/#\/schema\/logo\/image\/","url":"http:\/\/mgi-nouveau-site.mgi-labs.com\/wp-content\/uploads\/2022\/01\/Logo-MGI-Blue-Baseline.jpg","contentUrl":"http:\/\/mgi-nouveau-site.mgi-labs.com\/wp-content\/uploads\/2022\/01\/Logo-MGI-Blue-Baseline.jpg","width":842,"height":595,"caption":"MGI Digital Technology"},"image":{"@id":"https:\/\/mgi-fr.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/MGIonline\/","https:\/\/x.com\/MGI_HQ","https:\/\/www.linkedin.com\/company\/mgi-digital-graphic-technology\/","https:\/\/www.youtube.com\/channel\/UCqJTeVGo2EQ3NOCqFMekydA"]},{"@type":"Person","@id":"https:\/\/mgi-fr.com\/#\/schema\/person\/41ee3fb954ff7f83e6bddf4a40f00e8c","name":"Corinne","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35c9b8a47e518fa59c5c86426bbbb3fd63c5a79d7a7cba4db581487ea3498328?s=96&d=mm&r=g","caption":"Corinne"},"sameAs":["http:\/\/mgi-test-site.local"],"url":"https:\/\/mgi-fr.com\/en\/author\/corinne\/"}]}},"_links":{"self":[{"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/posts\/2937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/comments?post=2937"}],"version-history":[{"count":16,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/posts\/2937\/revisions"}],"predecessor-version":[{"id":13446,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/posts\/2937\/revisions\/13446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/media\/2752"}],"wp:attachment":[{"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/media?parent=2937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/categories?post=2937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mgi-fr.com\/en\/wp-json\/wp\/v2\/tags?post=2937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}